{"id":718,"date":"2024-06-16T00:25:36","date_gmt":"2024-06-15T22:25:36","guid":{"rendered":"https:\/\/new.1640.be\/?page_id=718"},"modified":"2024-10-03T18:45:36","modified_gmt":"2024-10-03T16:45:36","slug":"home-1640","status":"publish","type":"page","link":"https:\/\/1640.be\/en\/","title":{"rendered":"Home 1640"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Hero&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/WeAre-1640-be-VERT.png&#8221; title_text=&#8221;WeAre 1640 be &#8211; GREEN&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;83px||||false|false&#8221; custom_margin_tablet=&#8221;83px||||false|false&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;100% only for Rhode&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;ba4a6336-701f-47b8-bf5c-09da0ce28016&#8243; title_level=&#8221;h3&#8243; title_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; title_text_color=&#8221;#0e0c19&#8243; title_font_size=&#8221;24px&#8221; title_line_height=&#8221;1.3em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;22px&#8221; title_font_size_phone=&#8221;17px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;Always accessible, always available  &#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;f0c675ea-2574-4d0e-b725-30f8550a8550&#8243; title_level=&#8221;h4&#8243; title_font=&#8221;Proza Libre|Cormorant Garamond_weight||on|||||&#8221; title_text_color=&#8221;#006600&#8243; title_font_size=&#8221;14px&#8221; title_letter_spacing=&#8221;1px&#8221; title_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;13px&#8221; title_font_size_phone=&#8221;13px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#0e0c19%22:%91%22title_text_color%22%93,%22#2e5266%22:%91%22title_text_color%22%93}&#8221;][\/et_pb_heading][et_pb_text quote_border_color=&#8221;#6e8898&#8243; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;2c55a9c4-feed-423b-9edb-ae0b5b365cac&#8221; text_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; text_text_color=&#8221;#3c3a47&#8243; text_line_height=&#8221;1.75em&#8221; link_font=&#8221;|Proza Libre_weight|||||||&#8221; link_text_color=&#8221;#2e5266&#8243; quote_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"font-weight: 400;\">Listening to you, <\/span><b>building links<\/b><span style=\"font-weight: 400;\"> between people<\/span><b>, preserving the environmental,<\/b><span style=\"font-weight: 400;\"> residential and<\/span><b> safety character of <\/b><span style=\"font-weight: 400;\">our<\/span><b> community are<\/b><span style=\"font-weight: 400;\"> our<\/span><b> missions<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">At the dawn of this new term, our <\/span><b>enthusiasm<\/b><span style=\"font-weight: 400;\"> is intact! <\/span> <\/p>\n<p><span style=\"font-weight: 400;\">Led for 12 years by our <\/span><b>Mayor Pierre Rolin &#8216;<\/b><span style=\"font-weight: 400;\">1640.be&#8217; is a <\/span><b>team<\/b><span style=\"font-weight: 400;\"> of bilingual Rhodians, independent of all political parties and dedicated solely to<\/span><b> the well-being of Rhodians<\/b><span style=\"font-weight: 400;\">. <\/span> <\/p>\n<p><span style=\"font-weight: 400;\">Our <\/span><b>13 &#8216;1640.be&#8217; candidates<\/b><span style=\"font-weight: 400;\"> are running on the &#8220;<\/span><b>Mayor&#8217;s List <\/b><span style=\"font-weight: 400;\">&#8220;.<\/span> <\/p>\n<p><span style=\"font-weight: 400;\">Give us your confidence once again by voting for all our 13 candidates and we will continue to work for you every day&#8230;.<br \/> <\/span><\/p>\n<h3><b>&#8220;Our only party is Rhode.&#8221; <\/b><\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#contact&#8221; button_text=&#8221;I want to get involved&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;1bffc0fc-42a0-49d1-bd9a-ae3ade2d7206&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#18662d&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;Poppins|700|||||||&#8221; custom_padding=&#8221;12px|24px|12px|24px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|28px||20px|true|false&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/Banner-Home-1640-2.png&#8221; title_text=&#8221;Banner Home 1640 (2)&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Gallery&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#18662d&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Together&#8221; module_id=&#8221;realisations&#8221; module_class=&#8221;realisations&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;f0c675ea-2574-4d0e-b725-30f8550a8550&#8243; title_level=&#8221;h4&#8243; title_font=&#8221;Poppins|Cormorant Garamond_weight||on|||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#ffffff&#8221; title_font_size=&#8221;14px&#8221; title_letter_spacing=&#8221;1px&#8221; title_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;13px&#8221; title_font_size_phone=&#8221;13px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{%22#2e5266%22:%91%22title_text_color%22%93}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;Our achievements&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#FFFFFF&#8221; title_font_size=&#8221;50px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text quote_border_color=&#8221;#6e8898&#8243; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;2c55a9c4-feed-423b-9edb-ae0b5b365cac&#8221; text_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;1.75em&#8221; link_font=&#8221;|Proza Libre_weight|||||||&#8221; link_text_color=&#8221;#2e5266&#8243; quote_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;29px&#8221; header_3_line_height=&#8221;2.3em&#8221; header_4_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">For the past 12 years, we have been working tirelessly for our beautiful community, and we are pleased <\/span><b>to present some of our latest achievements<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Despite the various crises (Covid, war in Ukraine, energy crisis) and other unforeseen events (floods, fires, collapsed roads&#8230;), thanks to<b> our<\/b> constant<b> commitment <\/b>and <b>sound, far-sighted financial management<\/b>, we were able to carry out most of our program. <\/span><span style=\"font-weight: 400;\"><\/span><\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=&#8221;395,397,399,401,403,405,407,409,411,413,415,417,419,421,423,425,427,429,431,439,441,445,447,449,451,453,455,457,459,461,463,465,467,469,471,473,475,477,479,481,483,485,487,489,491,493,495,497,499,501,503,505,507,509,511,515,517,519,521,523,525,527,529,531,533,535,537,539,541,543,545,547,549,557,559,561,563,565,569,571,573,575,577,579,581,583,585,587,589,591,593,595,597,599,601,603,605,607,609,613,615,617,619,621,623,625,551,555,513,433,435,437,443&#8243; gallery_orderby=&#8221;rand&#8221; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;&#8211;et_global_body_font||||||||&#8221; title_text_align=&#8221;center&#8221; title_font_size=&#8221;12px&#8221; caption_font=&#8221;&#8211;et_global_body_font||||||||&#8221; caption_font_size=&#8221;8px&#8221; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjgzIiwiZW5hYmxlX2h0bWwiOiJvZmYifX0=@&#8221; button_text=&#8221;Discover our achievements 2018-2024&#8243; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.25.2&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;1bffc0fc-42a0-49d1-bd9a-ae3ade2d7206&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#006600&#8243; button_bg_color=&#8221;#FFFFFF&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;Poppins|700|||||||&#8221; custom_padding=&#8221;12px|24px|12px|24px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|28px||20px|true|false&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Initiatives and Programs&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;f0c675ea-2574-4d0e-b725-30f8550a8550&#8243; title_level=&#8221;h4&#8243; title_font=&#8221;Proza Libre|Cormorant Garamond_weight||on|||||&#8221; title_text_color=&#8221;#006600&#8243; title_font_size=&#8221;14px&#8221; title_letter_spacing=&#8221;1px&#8221; title_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;13px&#8221; title_font_size_phone=&#8221;13px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#0e0c19%22:%91%22title_text_color%22%93,%22#2e5266%22:%91%22title_text_color%22%93}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;Improving the well-being of Rhodians&#8221; module_id=&#8221;programme&#8221; module_class=&#8221;programme&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; title_text_color=&#8221;#0e0c19&#8243; title_font_size=&#8221;43px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#0e0c19%22:%91%22title_text_color%22,%22title_text_color%22%93}&#8221;][\/et_pb_heading][et_pb_text quote_border_color=&#8221;#6e8898&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;2c55a9c4-feed-423b-9edb-ae0b5b365cac&#8221; text_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; text_text_color=&#8221;#3c3a47&#8243; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.75em&#8221; link_font=&#8221;|Proza Libre_weight|||||||&#8221; link_text_color=&#8221;#2e5266&#8243; quote_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#2e5266%22:%91%22link_text_color%22%93,%22#0e0c19%22:%91%22header_text_color%22,%22header_4_text_color%22,%22header_3_text_color%22,%22header_2_text_color%22,%22header_5_text_color%22,%22header_6_text_color%22,%22quote_text_color%22%93,%22#3c3a47%22:%91%22text_text_color%22%93,%22#6e8898%22:%91%22quote_border_color%22%93,%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22%93}&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221;]<\/p>\n<p>Since our foundation in 2006, the 1640.be team has been involved in a variety of programs aimed at improving the quality of life for the people of Rhode-Saint-Gen\u00e8se. We have launched initiatives to enhance mobility, ensure safety, and offer enriching activities for all ages. Our projects include the creation of safe pedestrian zones, the organization of events and the provision of support services for young people and the elderly.  <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjI0MSIsImVuYWJsZV9odG1sIjoib2ZmIn19@&#8221; button_text=&#8221;Our priorities for 2025-2030&#8243; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;1bffc0fc-42a0-49d1-bd9a-ae3ade2d7206&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#006600&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;Proza Libre|700|||||||&#8221; custom_padding=&#8221;12px|24px|12px|24px|true|true&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|28px||20px|true|false&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text quote_border_color=&#8221;#6e8898&#8243; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;2c55a9c4-feed-423b-9edb-ae0b5b365cac&#8221; text_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; text_text_color=&#8221;#3c3a47&#8243; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.75em&#8221; link_font=&#8221;|Proza Libre_weight|||||||&#8221; link_text_color=&#8221;#2e5266&#8243; quote_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;161px||||false|false&#8221; custom_margin_tablet=&#8221;161px||||false|false&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22%93}&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221;]<\/p>\n<p>We firmly believe that every Rhodian deserves to live in a safe and dynamic environment. That&#8217;s why we work tirelessly to identify and solve local problems, while remaining independent of outside political influences. Our goal is to continue to serve the community with transparency and dedication.  <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; column_structure=&#8221;1_2,1_2&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; type=&#8221;1_2&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_video src=&#8221;https:\/\/www.youtube.com\/watch?v=i8b6F-r3_fU&amp;ab_channel=MiguelDelacroix&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_video][\/et_pb_column][et_pb_column _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; type=&#8221;1_2&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_video src=&#8221;https:\/\/www.youtube.com\/watch?v=pMlhxP4vO2o&amp;ab_channel=MiguelDelacroix&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Blog&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f4f4f4&#8243; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;News  Announcements&#8221; module_id=&#8221;news&#8221; module_class=&#8221;news&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; title_text_color=&#8221;#0e0c19&#8243; title_font_size=&#8221;50px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_blog fullwidth=&#8221;off&#8221; posts_number=&#8221;3&#8243; excerpt_length=&#8221;100&#8243; show_more=&#8221;on&#8221; show_author=&#8221;off&#8221; show_date=&#8221;off&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;0348c28c-34b9-43d0-8c6e-c8db6c12d77f&#8221; header_font=&#8221;Poppins|300|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;24px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; meta_font=&#8221;Poppins|Proza Libre_weight|||||||&#8221; meta_text_color=&#8221;#006600&#8243; read_more_font=&#8221;Proza Libre|700|||||||&#8221; read_more_text_color=&#8221;#006600&#8243; pagination_font=&#8221;Proza Libre|700|||||||&#8221; pagination_text_color=&#8221;#6e8898&#8243; pagination_font_size=&#8221;18px&#8221; header_font_size_tablet=&#8221;18px&#8221; header_font_size_phone=&#8221;14.5px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; pagination_font_size_tablet=&#8221;15px&#8221; pagination_font_size_phone=&#8221;14px&#8221; pagination_font_size_last_edited=&#8221;on|tablet&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blog][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6Ijg3IiwiZW5hYmxlX2h0bWwiOiJvZmYifX0=@&#8221; button_text=&#8221;Rhode&#039;s news&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.25.2&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;1bffc0fc-42a0-49d1-bd9a-ae3ade2d7206&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#006600&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;Proza Libre|700|||||||&#8221; custom_padding=&#8221;12px|24px|12px|24px|true|true&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover_enabled=&#8221;off|desktop&#8221; custom_padding__hover=&#8221;|28px||20px|true|false&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Team&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Our candidates&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;f0c675ea-2574-4d0e-b725-30f8550a8550&#8243; title_level=&#8221;h4&#8243; title_font=&#8221;Proza Libre|Cormorant Garamond_weight||on|||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#006600&#8243; title_font_size=&#8221;14px&#8221; title_letter_spacing=&#8221;1px&#8221; title_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;13px&#8221; title_font_size_phone=&#8221;13px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22#0e0c19%22:%91%22title_text_color%22%93,%22#2e5266%22:%91%22title_text_color%22%93}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;Meet our team&#8221; module_id=&#8221;team&#8221; module_class=&#8221;team&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#0e0c19&#8243; title_font_size=&#8221;50px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_4,1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text quote_border_color=&#8221;#6e8898&#8243; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;2c55a9c4-feed-423b-9edb-ae0b5b365cac&#8221; text_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; text_text_color=&#8221;#3c3a47&#8243; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.9em&#8221; link_font=&#8221;|Proza Libre_weight|||||||&#8221; link_text_color=&#8221;#2e5266&#8243; quote_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; quote_text_color=&#8221;#0e0c19&#8243; header_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;72px&#8221; header_line_height=&#8221;1.15em&#8221; header_2_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_2_text_color=&#8221;#0e0c19&#8243; header_2_font_size=&#8221;50px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_3_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_3_text_color=&#8221;#0e0c19&#8243; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_4_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_4_text_color=&#8221;#0e0c19&#8243; header_4_font_size=&#8221;24px&#8221; header_4_line_height=&#8221;1.4em&#8221; header_5_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_5_text_color=&#8221;#0e0c19&#8243; header_5_font_size=&#8221;18px&#8221; header_5_line_height=&#8221;1.4em&#8221; header_6_font=&#8221;Cormorant Garamond|Cormorant Garamond_weight|||||||&#8221; header_6_text_color=&#8221;#0e0c19&#8243; header_6_line_height=&#8221;1.5em&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;800px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;15px&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;40px&#8221; header_font_size_phone=&#8221;24px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;28px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_tablet=&#8221;22px&#8221; header_3_font_size_phone=&#8221;17px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;15px&#8221; header_4_font_size_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;15px&#8221; header_5_font_size_phone=&#8221;14px&#8221; header_5_font_size_last_edited=&#8221;on|desktop&#8221; header_6_font_size_tablet=&#8221;13px&#8221; header_6_font_size_phone=&#8221;13px&#8221; header_6_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Managing the community is a <\/span><b>teamwork<\/b><span style=\"font-weight: 400;\"> and a team only works well when all its members share the same vision. <\/span> <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">12 years ago, our Mayor, Pierre Rolin, created with Miguel Delacroix (alderman) the team known as &#8220;<\/span><b>1640.be<\/b><span style=\"font-weight: 400;\">&#8220;. <\/span> <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Today, we need you to vote in favor of <\/span><b>the 13 members of our team <\/b><span style=\"font-weight: 400;\">so that together we can continue to improve the quality of life for all Rhodians!<\/span><span _d-id=\"402\" class=\"--l --r popup_anchor_highlight__with_key_targetContextEditing\"><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">The 13 members of our team (11 from the municipality and 2 from the CPAS) are <\/span><b>bilingual, hard-working and independent <\/b><span style=\"font-weight: 400;\">from all political parties.<\/span><span _d-id=\"402\" class=\"--l --r popup_anchor_highlight__with_key_targetContextEditing\"><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">They have no national or international political ambitions; all their time and energy <\/span><b>will be devoted to Rhode<\/b><span style=\"font-weight: 400;\">! <\/span> <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">They are complementary and experienced: lawyers, finance experts, entrepreneurs, editors, sportsmen and women, engineers, photographers, active in youth movements and voluntary work.<\/span><span _d-id=\"402\" class=\"--l --r popup_anchor_highlight__with_key_targetContextEditing\"><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Together, they form a close-knit team determined to move Rhode forward.<\/span><\/p>\n<p style=\"text-align: justify;\"><span _d-id=\"402\" class=\"--l --r popup_anchor_highlight__with_key_targetContextEditing\"><span style=\"font-weight: 400;\">The <\/span><b>13th<\/b><span style=\"font-weight: 400;\"> of October, as authorized by law, vote for all our <\/span><b>13<\/b><span style=\"font-weight: 400;\"> candidates on the <\/span><b>&#8220;Mayor&#8217;s List&#8221;.<\/b> <\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Pierre Rolin&#8221; position=&#8221;Mayor&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; body_link_font_size=&#8221;12px&#8221; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#pierre\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">Rhode and Pierre<\/a><\/p>\n<p>[\/et_pb_team_member][et_pb_team_member name=&#8221;Julien Galand&#8221; position=&#8221;Counsellor CPAS&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/3-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#julien\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Julien  <\/a><\/p>\n<p>[\/et_pb_team_member][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Miguel Delacroix&#8221; position=&#8221;Alderman&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/2.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#miguel\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Miguel<\/a><\/p>\n<p>[\/et_pb_team_member][et_pb_team_member name=&#8221;Celine Van der Eecken&#8221; position=&#8221;Communal&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/4-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#celine\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Celine  <\/a>[\/et_pb_team_member][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Dominique Neirynck&#8221; position=&#8221;Local counsellor&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/5-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#dominique\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Dominique  <\/a><\/p>\n<p>[\/et_pb_team_member][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Tanguy Van Vlasselaer&#8221; position=&#8221;Communal&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/6-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#tanguy\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Tanguy  <\/a>[\/et_pb_team_member][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Fran\u00e7oise Gauthier&#8221; position=&#8221;Local counsellor&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/7-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#francoise\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Fran\u00e7oise  <\/a><\/p>\n<p>[\/et_pb_team_member][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Didier Vandenbosch&#8221; position=&#8221;Communal&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/8-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#didier\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Didier  <\/a>[\/et_pb_team_member][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Stephanie Van Rossum&#8221; position=&#8221;Communal&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/9-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#stephanie\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Stephanie  <\/a>[\/et_pb_team_member][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Patrick Ipsen&#8221; position=&#8221;Communal&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/10-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#patrick\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Patrick  <\/a>[\/et_pb_team_member][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Caroline Louveaux&#8221; position=&#8221;Local counsellor&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/11-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#caroline\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Caroline  <\/a><\/p>\n<p>[\/et_pb_team_member][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Anne Troussel&#8221; position=&#8221;President of the CPAS&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/12-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#anne\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Anne  <\/a><\/p>\n<p>[\/et_pb_team_member][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_team_member name=&#8221;Olivier De Vos&#8221; position=&#8221;CPAS&#8221; image_url=&#8221;https:\/\/1640.be\/wp-content\/uploads\/2024\/09\/13-1.jpg&#8221; icon_color=&#8221;#2e5266&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;5ca6fc8d-ab90-4428-bda7-dfb0ef32c494&#8243; header_level=&#8221;h5&#8243; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;15px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; position_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;300px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;20px|20px|20px|20px|true|true&#8221; header_font_size_tablet=&#8221;16px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|tablet&#8221; custom_css_member_image=&#8221;margin: 0 auto 20px;&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_vertical=&#8221;24px&#8221; box_shadow_blur=&#8221;72px&#8221; box_shadow_spread=&#8221;-12px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.12)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-36fd78a7-34bc-404d-873c-dafa34efaae5%22:%91%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22,%22icon_color%22%93,%22gcid-7cadd8b3-5228-48e4-90c4-212d09232f7b%22:%91%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22,%22header_text_color%22%93,%22gcid-79b39b81-644f-4ab7-865f-b460373c4fde%22:%91%22position_text_color%22,%22position_text_color%22,%22position_text_color%22,%22position_text_color%22%93}&#8221;]<\/p>\n<p><a href=\"https:\/\/1640.be\/en\/the-team-candidates\/#olivier\" class=\"et_pb_button et_pb_button_0 et_pb_bg_layout_light\">  Rhode and Olivier<\/a><\/p>\n<p>[\/et_pb_team_member][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.17.1&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Gallery&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#efefef&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.17.6&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.4&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Follow and share&#8221; module_id=&#8221;realisations&#8221; module_class=&#8221;realisations&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;f0c675ea-2574-4d0e-b725-30f8550a8550&#8243; title_level=&#8221;h4&#8243; title_font=&#8221;Poppins|Cormorant Garamond_weight||on|||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#006600&#8243; title_font_size=&#8221;14px&#8221; title_letter_spacing=&#8221;1px&#8221; title_line_height=&#8221;1.4em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;13px&#8221; title_font_size_phone=&#8221;13px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{%22#2e5266%22:%91%22title_text_color%22%93}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;Living in Rhode&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_level=&#8221;h2&#8243; title_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; title_text_align=&#8221;center&#8221; title_text_color=&#8221;#0e0c19&#8243; title_font_size=&#8221;50px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_code _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<div class=\"cff-wrapper\">\t<div id=\"cff-visual-header-316958155041143\" class=\"cff-visual-header cff-has-name cff-has-about\">\n\t\t\t\t\t\t<div class=\"cff-header-inner-wrap\">\n\t\t\t\t\t\t<div class=\"cff-header-text\" >\n\n\t\t\t\t            <a href=\"https:\/\/facebook.com\/316958155041143\" target=\"_blank\" rel=\"nofollow noopener\" title=\"\" class=\"cff-header-name\"><h3 style=\"font-size:inheritpx;\"><\/h3><\/a>\n\t\t\t\t        \t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"cff-wrapper-ctn \" ><div id=\"cff\"  class=\"cff cff-list-container cff-masonry masonry-2-tablet cff-masonry-js cff-default-styles  cff-mob-cols-1\"   style=\"width:100%;\"   data-char=\"400\" ><div class=\"cff-error-msg\">\n\t<div>\n\t\t<i class=\"fa fa-lock\" aria-hidden=\"true\" style=\"margin-right: 5px;\"><\/i><b>This message is only visible to admins.<\/b><br\/>\n\t\tProblem displaying Facebook posts.\t\t\t\t\t<br\/><a href=\"javascript:void(0);\" id=\"cff-show-error\" onclick=\"cffShowError()\">Click to show error<\/a>\n\t\t\t<script type=\"text\/javascript\">function cffShowError() { document.getElementById(\"cff-error-reason\").style.display = \"block\"; document.getElementById(\"cff-show-error\").style.display = \"none\"; }<\/script>\n\t\t\t<\/div>\n\t\t\t<div id=\"cff-error-reason\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<b>Error:<\/b> No posts available for this Facebook ID\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n<\/div>\n<div class=\"cff-posts-wrap\">\n<div class=\"cff-likebox cff-bottom\" >\n\t\t<iframe title=\"Likebox Iframe\" src=\"\" class=\"fb_iframe_widget\" data-likebox-id=\"316958155041143\" data-likebox-width=\"300\" data-likebox-header=\"\" data-hide-cover=\"\" data-hide-cta=\"\" data-likebox-faces=\"\" data-height=\"130\" data-locale=\"en_US\" scrolling=\"no\" allowTransparency=\"true\" allow=\"encrypted-media\" ><\/iframe>\n<\/div>\n<\/div><input class=\"cff-pag-url\" type=\"hidden\" data-locatornonce=\"c6f586e14d\" data-cff-shortcode=\"{&quot;feed&quot;: &quot;2&quot;}\" data-post-id=\"718\" data-feed-id=\"316958155041143\"><\/div><\/div><div class=\"cff-clear\"><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Contact&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; collapsed=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Contact us&#8221; module_id=&#8221;contact&#8221; module_class=&#8221;contact&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;c33f07d9-41e0-421a-8799-5799df695cce&#8221; title_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; title_text_color=&#8221;#0e0c19&#8243; title_font_size=&#8221;50px&#8221; title_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||10px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;5138c454-be54-4233-bd3b-f8e6a8747976&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_contact_form email=&#8221;contact@1640.be&#8221; custom_message=&#8221;Message : %%message%%: %%Name%%: %%Email%%&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;347de7c5-8eec-4fb2-89ad-e07c220a4ead&#8221; _unique_id=&#8221;653e01dd-6bd4-4e62-b530-40e83ea72455&#8243; form_field_background_color=&#8221;RGBA(255,255,255,0)&#8221; form_field_text_color=&#8221;#3c3a47&#8243; form_field_custom_margin=&#8221;||20px||false|false&#8221; form_field_custom_padding=&#8221;18px||18px||true|false&#8221; title_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; title_text_color=&#8221;#0e0c19&#8243; title_font_size=&#8221;50px&#8221; title_line_height=&#8221;1.2em&#8221; captcha_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; form_field_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; form_field_font_size=&#8221;16px&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#006600&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;100px&#8221; button_font=&#8221;Proza Libre|700|||||||&#8221; button_custom_margin=&#8221;10px||||false|false&#8221; button_custom_padding=&#8221;12px|24px|12px|24px|true|true&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;20px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;on|6px|6px|6px|6px&#8221; border_width_all=&#8221;2px&#8221; border_color_all=&#8221;rgba(0,0,0,0.08)&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Name&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;Email Address&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Message&#8221; field_title=&#8221;Message&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||20px||false|false&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;73121f80-a3ef-4484-8763-c3f18e3c56d2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Email&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf0e0;||fa||900&#8243; icon_color=&#8221;#006600&#8243; image_icon_width=&#8221;32px&#8221; icon_alignment=&#8221;left&#8221; content_max_width=&#8221;100%&#8221; module_class=&#8221;ai_ignore_all&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Poppins|300|||||||&#8221; body_text_color=&#8221;#006600&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; image_icon_background_color__hover_enabled=&#8221;off|desktop&#8221;]<\/p>\n<p><a href=\"mailto:contact@1640.be\">contact@1640.be<\/a><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8221;Social&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe0a0;||divi||400&#8243; icon_color=&#8221;#006600&#8243; image_icon_width=&#8221;32px&#8221; icon_alignment=&#8221;left&#8221; content_max_width=&#8221;100%&#8221; module_class=&#8221;ai_ignore_all&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;212b201d-2c34-41bd-936c-851b7357d08b&#8221; header_font=&#8221;Poppins|Cormorant Garamond_weight|||||||&#8221; header_text_color=&#8221;#0e0c19&#8243; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.4em&#8221; body_font=&#8221;Proza Libre|Proza Libre_weight|||||||&#8221; body_text_color=&#8221;#3c3a47&#8243; body_font_size=&#8221;16px&#8221; body_line_height=&#8221;1.75em&#8221; body_link_text_color=&#8221;#2e5266&#8243; background_mask_style=&#8221;wave&#8221; image_icon_custom_margin=&#8221;||||false|false&#8221; image_icon_custom_padding=&#8221;||||false|false&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation=&#8221;off&#8221; header_font_size_tablet=&#8221;15px&#8221; header_font_size_phone=&#8221;13px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; body_font_size_tablet=&#8221;15px&#8221; body_font_size_phone=&#8221;14px&#8221; body_font_size_last_edited=&#8221;on|desktop&#8221; border_radii_image=&#8221;on|6px|6px|6px|6px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; image_icon_background_color__hover_enabled=&#8221;off|desktop&#8221;][\/et_pb_blurb][et_pb_social_media_follow icon_color=&#8221;#006600&#8243; module_class=&#8221;ai_ignore_all&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;9a2c7b49-38da-4a8e-a698-40ad4873179f&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/1640.be&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;7157d47b-1430-4c96-a27f-da782814b26a&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/seizequarante?igsh=ZDNubmlwcTYxZGZy&#8221; _builder_version=&#8221;4.25.2&#8243; _module_preset=&#8221;7157d47b-1430-4c96-a27f-da782814b26a&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Listening to you, building links between people, preserving the environmental, residential and safety character of our community are our missions. At the dawn of this new term, our enthusiasm is intact! Led for 12 years by our Mayor Pierre Rolin &#8216;1640.be&#8217; is a team of bilingual Rhodians, independent of all political parties and dedicated solely [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-718","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/1640.be\/en\/wp-json\/wp\/v2\/pages\/718"}],"collection":[{"href":"https:\/\/1640.be\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/1640.be\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/1640.be\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/1640.be\/en\/wp-json\/wp\/v2\/comments?post=718"}],"version-history":[{"count":73,"href":"https:\/\/1640.be\/en\/wp-json\/wp\/v2\/pages\/718\/revisions"}],"predecessor-version":[{"id":1315,"href":"https:\/\/1640.be\/en\/wp-json\/wp\/v2\/pages\/718\/revisions\/1315"}],"wp:attachment":[{"href":"https:\/\/1640.be\/en\/wp-json\/wp\/v2\/media?parent=718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}